{"id":32087,"date":"2019-11-11T11:53:37","date_gmt":"2019-11-11T14:53:37","guid":{"rendered":"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5.jpeg"},"modified":"2019-11-11T11:53:37","modified_gmt":"2019-11-11T14:53:37","slug":"capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-mercado-central-5","status":"inherit","type":"attachment","link":"https:\/\/www.inet.edu.ar\/index.php\/come-pescado-argentino-en-el-mercado-central\/capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-mercado-central-5\/#main","title":{"rendered":"Capacitaci\u00f3n en alimentaci\u00f3n y cocina con pescado en el Mercado Central (5)"},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"class_list":["post-32087","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-240x180.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-240x180.jpeg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-768x576.jpeg 768w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-468x351.jpeg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5.jpeg 1032w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1032,"height":774,"file":"2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5.jpeg","sizes":{"thumbnail":{"file":"Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-150x100.jpeg","width":150,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-150x100.jpeg"},"medium":{"file":"Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-240x180.jpeg","width":240,"height":180,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-240x180.jpeg"},"medium_large":{"file":"Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-768x576.jpeg","width":768,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-768x576.jpeg"},"large":{"file":"Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-468x351.jpeg","width":468,"height":351,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5-468x351.jpeg"},"full":{"file":"Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5.jpeg","width":1032,"height":774,"mime_type":"image\/jpeg","source_url":"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":32080,"source_url":"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2019\/11\/Capacitacion-en-alimentacion-y-cocina-con-pescado-en-el-Mercado-Central-5.jpeg","_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/32087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=32087"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":32080,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/32080"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}