{"id":17919,"date":"2016-12-20T12:35:31","date_gmt":"2016-12-20T15:35:31","guid":{"rendered":"https:\/\/www.inet.edu.ar\/?p=17919"},"modified":"2016-12-20T13:48:03","modified_gmt":"2016-12-20T16:48:03","slug":"comienzan-las-obras-en-el-polo-educativo-de-lanus","status":"publish","type":"post","link":"https:\/\/www.inet.edu.ar\/index.php\/comienzan-las-obras-en-el-polo-educativo-de-lanus\/","title":{"rendered":"Comienzan las obras en el Polo Educativo de Lan\u00fas"},"content":{"rendered":"<p>Lan\u00fas<\/p>\n<p>En el d\u00eda de hoy comenzaron las obras para construir el Polo Educativo en el predio ubicado en Osorio y Moreno, ubicado en Villa Jard\u00edn. Recorrieron\u00a0el lugar el director nacional de Formaci\u00f3n Profesional, Fabi\u00e1n Prieto; y el intendente de Lan\u00fas, N\u00e9stor Gruindetti; junto al\u00a0subsecretario nacional de Juventud, Pedro Robledo; y al secretario local de Desarrollo Urbano, Carlos Silva.<\/p>\n<p>Gracias a un convenio firmado entre el Ministerio de Educaci\u00f3n y Deportes de la Naci\u00f3n, y el Municipio, con apoyo del gobierno de Provincia de Buenos Aires,\u00a0Villa Jard\u00edn contar\u00e1 con un centro educativo que incluir\u00e1\u00a0una escuela Secundaria T\u00e9cnica, una escuela de Enfermer\u00eda y un centro de Energ\u00edas Renovables. Este proyecto representa para Villa Jard\u00edn un importante avance en cuanto a la urbanizaci\u00f3n del barrio, y se suma a otros, como por ejemplo la construcci\u00f3n del Puente Osorio.<\/p>\n<p>Luego de una primera etapa en la que se realiz\u00f3 la limpieza de este terreno que hab\u00eda estado abandonado, se construir\u00e1n una Escuela Secundaria y la Casa del Futuro.<\/p>\n<p>Al referirse al proyecto educativo, Prieto indic\u00f3: <em>\u00abEl INET va a financiar instituciones vinculadas con la formaci\u00f3n t\u00e9cnica, aqu\u00ed se comenzar\u00e1 a construir una escuela secundaria con orientaci\u00f3n textil, un centro de formaci\u00f3n profesional para adultos, una escuela de enfermer\u00eda que va a contar con telemedicina, un centro de transferencia de energ\u00eda renovable para capacitar a ciudadanos que quieran formarse\u00bb.<\/em><\/p>\n<p><em>\u201cHab\u00edamos pensado esto hace un tiempo, era un sue\u00f1o que ten\u00edamos y, con la ayuda del Gobierno Nacional y del INET podemos encarar. Hoy, despu\u00e9s de meses de trabajo, de la firma de convenio, podemos decir que esto comienza y consolida el cambio que comenz\u00f3 hace un a\u00f1o\u201d<\/em>, destac\u00f3 Grindetti.<\/p>\n<p>Con respecto a\u00a0la Casa\u00a0del Futuro, Robledo destac\u00f3: <em>\u201cPonemos mucho trabajo en aquellos j\u00f3venes que dejaron sus estudios o que todav\u00eda no consiguen trabajo, los capacitamos. Que funcione en el Polo Educativo tambi\u00e9n es mejor porque es trabajar con el INET, con la escuela y con las nuevas tecnolog\u00edas\u201d<\/em>.<\/p>\n<p>El plan de obras del Polo Educativo se realizar\u00e1 por etapas. Hoy se dio a la primera y ya se encuentra en proceso de licitaci\u00f3n la segunda instancia que incluir\u00e1 la construcci\u00f3n de las naves restantes.<\/p>\n<p><strong>Noticias relacionadas<\/strong><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/index.php\/se-lanzo-un-polo-educativo-entre-nacion-provincia-de-buenos-aires-y-lanus\/\">\u00abSe lanz\u00f3 un Polo Educativo entre Naci\u00f3n, Provincia de Buenos Aires y Lan\u00fas\u00bb<\/a><\/p>\n<p><strong>Galer\u00eda de im\u00e1genes<\/strong><\/p>\n\n\t\t<style>\n\t\t\t#gallery-1 {\n\t\t\t\tmargin: auto;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-item {\n\t\t\t\tfloat: left;\n\t\t\t\tmargin-top: 10px;\n\t\t\t\ttext-align: center;\n\t\t\t\twidth: 33%;\n\t\t\t}\n\t\t\t#gallery-1 img {\n\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t}\n\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\tmargin-left: 0;\n\t\t\t}\n\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t<\/style>\n\t\t<div id='gallery-1' class='gallery galleryid-17919 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.inet.edu.ar\/index.php\/comienzan-las-obras-en-el-polo-educativo-de-lanus\/img-20161220-wa0005\/#main'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0005-240x180.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0005-240x180.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0005-768x576.jpg 768w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0005-468x351.jpg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0005.jpg 1280w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.inet.edu.ar\/index.php\/comienzan-las-obras-en-el-polo-educativo-de-lanus\/img-20161220-wa0004\/#main'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0004-240x180.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0004-240x180.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0004-768x576.jpg 768w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0004-468x351.jpg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0004.jpg 1280w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.inet.edu.ar\/index.php\/comienzan-las-obras-en-el-polo-educativo-de-lanus\/img-20161220-wa0001\/#main'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0001-240x180.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0001-240x180.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0001-768x576.jpg 768w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0001-468x351.jpg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0001.jpg 1280w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.inet.edu.ar\/index.php\/comienzan-las-obras-en-el-polo-educativo-de-lanus\/img-20161220-wa0003\/#main'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"180\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0003-240x180.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0003-240x180.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0003-768x576.jpg 768w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0003-468x351.jpg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/IMG-20161220-WA0003.jpg 1280w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.inet.edu.ar\/index.php\/comienzan-las-obras-en-el-polo-educativo-de-lanus\/3-2\/#main'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"160\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/3-240x160.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/3-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/3-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/3-468x312.jpg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/3.jpg 640w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a>\n\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t<a href='https:\/\/www.inet.edu.ar\/index.php\/comienzan-las-obras-en-el-polo-educativo-de-lanus\/2-6\/#main'><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"160\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/2-1-240x160.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/2-1-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/2-1-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/2-1-468x312.jpg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/12\/2-1.jpg 640w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a>\n\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Lan\u00fas En el d\u00eda de hoy comenzaron las obras para construir el Polo Educativo en el predio ubicado en Osorio y Moreno, ubicado en Villa Jard\u00edn. Recorrieron\u00a0el lugar el director nacional de Formaci\u00f3n Profesional, Fabi\u00e1n Prieto; y el intendente de Lan\u00fas, N\u00e9stor Gruindetti; junto al\u00a0subsecretario nacional de Juventud, Pedro Robledo; y al secretario local de [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":17924,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,14],"tags":[],"class_list":["post-17919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-noticias-fijas"],"_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/17919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=17919"}],"version-history":[{"count":5,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/17919\/revisions"}],"predecessor-version":[{"id":17933,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/17919\/revisions\/17933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/17924"}],"wp:attachment":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=17919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=17919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=17919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}