{"id":3604,"date":"2014-04-29T15:25:30","date_gmt":"2014-04-29T18:25:30","guid":{"rendered":"https:\/\/www.inet.edu.ar\/?p=3604"},"modified":"2014-04-29T15:25:30","modified_gmt":"2014-04-29T18:25:30","slug":"1-encuentro-2014-de-la-operatoria-del-regimen-de-credito-fiscal-2014","status":"publish","type":"post","link":"https:\/\/www.inet.edu.ar\/index.php\/1-encuentro-2014-de-la-operatoria-del-regimen-de-credito-fiscal-2014\/","title":{"rendered":"1\u00b0 Encuentro 2014 de la operatoria del R\u00e9gimen de Cr\u00e9dito Fiscal 2014"},"content":{"rendered":"<p><span style=\"line-height: 1.21em;\">El d\u00eda 25 de abril del a\u00f1o \u00a02014 un equipo t\u00e9cnico el INET \u00a0realiz\u00f3 el primer encuentro del a\u00f1o por las nuevas operatorias del R\u00e9gimen de Cr\u00e9dito Fiscal, en el la sala de Microcine de la sede de YPF en la provincia de Neuqu\u00e9n.<\/span><\/p>\n<p><span style=\"line-height: 1.21em;\">La empresa YPF patrocina a los establecimientos educativos de las provincias en donde ellos operan fuertemente la exploraci\u00f3n y explotaci\u00f3n petrol\u00edfera.<\/span><\/p>\n<p><span style=\"line-height: 1.21em;\">Como autoridad de YPF particip\u00f3 el Gerente de Administraciones P\u00fablicas, Diego Ondarts. Asistieron tambi\u00e9n 47 representantes de 36 establecimientos de Neuqu\u00e9n y R\u00edo Negro, entre las cuales estaban escuelas del Bols\u00f3n y Bariloche. Las instituciones convocadas eran Centros de Formaci\u00f3n Profesional, Escuelas T\u00e9cnicas , Escuelas Agrot\u00e9cnicas e Instituciones de Tecnicaturas Superiores de las provincias.<\/span><\/p>\n<p><span style=\"line-height: 1.21em;\">Esta ha sido una nueva edici\u00f3n de otros encuentros ya realizados a lo largo de estos a\u00f1os en los cuales los referentes t\u00e9cnico-pol\u00edticos educativos de las provincias, solicitan informaci\u00f3n ampliada cada vez que se lanza luna nueva operatoria anual.<\/span><\/p>\n<p><span style=\"line-height: 1.21em;\">Parte de los fines de estos encuentros es conocer cu\u00e1les son los objetivos del R\u00e9gimen y cu\u00e1les son los requisitos b\u00e1sicos al momento de presentar proyectos.<\/span><\/p>\n<p><strong style=\"line-height: 1.21em;\">Para m\u00e1s informaci\u00f3n<\/strong><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/credito-fiscal\/\">https:\/\/www.inet.edu.ar\/credito-fiscal\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda 25 de abril del a\u00f1o \u00a02014 un equipo t\u00e9cnico el INET \u00a0realiz\u00f3 el primer encuentro del a\u00f1o por las nuevas operatorias del R\u00e9gimen de Cr\u00e9dito Fiscal, en el la sala de Microcine de la sede de YPF en la provincia de Neuqu\u00e9n. La empresa YPF patrocina a los establecimientos educativos de las provincias [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3604","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=3604"}],"version-history":[{"count":1,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3604\/revisions"}],"predecessor-version":[{"id":3605,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/3604\/revisions\/3605"}],"wp:attachment":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=3604"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=3604"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=3604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}