{"id":4439,"date":"2014-07-25T15:28:37","date_gmt":"2014-07-25T18:28:37","guid":{"rendered":"https:\/\/www.inet.edu.ar\/?p=4439"},"modified":"2017-01-25T17:01:53","modified_gmt":"2017-01-25T20:01:53","slug":"se-realizara-la-entrega-de-premios-y-defensa-de-trabajos-de-las-olimpiadas-de-contenidos-en-internet-2013","status":"publish","type":"post","link":"https:\/\/www.inet.edu.ar\/index.php\/se-realizara-la-entrega-de-premios-y-defensa-de-trabajos-de-las-olimpiadas-de-contenidos-en-internet-2013\/","title":{"rendered":"Se realizar\u00e1 la entrega de premios y la defensa de trabajos de las Olimpiadas de contenidos en Internet 2013"},"content":{"rendered":"<p>El d\u00eda jueves 7 de agosto se realizar\u00e1 la defensa de trabajos y la entrega de premios de las <strong>Olimpiadas de contenidos en Internet 2013<\/strong>, en la sede del <strong>INET<\/strong>.<\/p>\n<p>Esta convocatoria permitir\u00e1 por un lado, que alumnos y docentes de los equipos finalistas cuenten al jurado las experiencias vividas en las distintas etapas de desarrollo de los contenidos presentados,\u00a0<span style=\"line-height: 1.21em;\">y a su vez, los participantes de distintos puntos de nuestro pa\u00eds tendr\u00e1n la oportunidad de interactuar entre s\u00ed entre si.\u00a0<\/span><span style=\"line-height: 1.21em;\">Los directivos de las escuelas involucradas ser\u00e1n parte de la coordinaci\u00f3n del evento<\/span><\/p>\n<p>En este cierre de certamen todos los alumnos y docentes involucrados recibir\u00e1n sus felicitaciones pues hayan ganado un premio o no, representan lo bueno que se puede hacer en las escuelas argentinas.<\/p>\n<h1><strong>\u00a0L<span style=\"line-height: 1.21em;\">istado de finalistas (por orden alfab\u00e9tico):<\/span><\/strong><\/h1>\n<ul>\n<li><strong>Adolescentes y Alcohol, Una problem\u00e1tica de VLA<br \/>\n<\/strong>C.P.E.M. N\u00ba 68 &#8211; Villa La Angostura \u2013 Neuqu\u00e9n<\/li>\n<li><strong>ALERTA FACEBOOK II<br \/>\n<\/strong>E.E.S N\u00ba 18 &#8216;Eugenia Rodriguez de Zlachevsky&#8217; &#8211; Santa Sylvina &#8211; Chaco<\/li>\n<li><strong>Aprendiendo con Arduino<br \/>\n<\/strong>E.E.T. N\u00ba 2 Patricias Argentinas &#8211; Jun\u00edn &#8211; Buenos Aires<\/li>\n<li><strong>H2O como combustible<br \/>\n<\/strong>E.T. N\u00ba 3 Maria Sanchez de Thompson &#8211; Ciudad de Buenos Aires<\/li>\n<li><strong>I.M.E. Impulso Motriz Electrico<br \/>\n<\/strong>I.P.E.M. N\u00ba221 \u00a8San Carlos\u00a8 &#8211; Jovita &#8211; C\u00f3rdoba<\/li>\n<li><strong>Ladrillos Alivianados con Diatomita<br \/>\n<\/strong>Escuela Industrial &#8216;Domingo F. Sarmiento&#8217; &#8211; San Juan &#8211; San Juan<\/li>\n<li><strong>Las TIC\u00b4s en funci\u00f3n de la literatura<br \/>\n<\/strong>EESO N\u00b0 637 &#8211; Santa Fe &#8211; Santa Fe<\/li>\n<li><strong>Micro \u2013 USB<br \/>\n<\/strong>Escuela Industrial &#8216;Domingo F. Sarmiento&#8217; \u2013 San Juan- San Juan<\/li>\n<li><strong>Mirada Sensorial<br \/>\n<\/strong>E.E.S.T N\u00b01 &#8216;Gral. Manuel Belgrano&#8217; &#8211; Las Flores &#8211; Buenos Aires<\/li>\n<li><strong>Rob\u00f3tica en la escuela<br \/>\n<\/strong>E.E.T. N\u00ba 2 &#8211; Patricias Argentinas &#8211; Jun\u00edn &#8211; Buenos Aires<\/li>\n<li><strong>Rojo que te quiero rojo<br \/>\n<\/strong>Escuela de Minas Dr. Horacio Carrillo &#8211; San Salvador de Jujuy &#8211; Jujuy<\/li>\n<li><strong>S.O.S. METABOLISMO<br \/>\n<\/strong>Escuela Agrot\u00e9cnica N\u00ba 51 &#8216;Gdor. Maci\u00e1&#8217; &#8211; Maci\u00e1 &#8211; Entre R\u00edos<\/li>\n<\/ul>\n<div><strong><span style=\"line-height: 14.713600158691406px;\">La inscripci\u00f3n para la edici\u00f3n 2014 est\u00e1 abierta.<\/span><\/strong><\/div>\n<div><\/div>\n<div><\/div>\n<p><strong style=\"font-size: 1.25em; line-height: 1.31em;\">Para m\u00e1s informaci\u00f3n:<\/strong><\/p>\n<div><\/div>\n<div><a href=\"http:\/\/oni.escuelas.edu.ar\/\">Olimpiadas de Contenidos en Internet<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda jueves 7 de agosto se realizar\u00e1 la defensa de trabajos y la entrega de premios de las Olimpiadas de contenidos en Internet 2013, en la sede del INET. Esta convocatoria permitir\u00e1 por un lado, que alumnos y docentes de los equipos finalistas cuenten al jurado las experiencias vividas en las distintas etapas de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4439","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/4439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=4439"}],"version-history":[{"count":9,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/4439\/revisions"}],"predecessor-version":[{"id":18502,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/4439\/revisions\/18502"}],"wp:attachment":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=4439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=4439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=4439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}