{"id":4600,"date":"2014-08-26T17:04:31","date_gmt":"2014-08-26T20:04:31","guid":{"rendered":"https:\/\/www.inet.edu.ar\/?p=4600"},"modified":"2017-01-25T17:34:10","modified_gmt":"2017-01-25T20:34:10","slug":"se-realizaron-capacitaciones-en-tecnologias-para-la-discapacidad-en-salta","status":"publish","type":"post","link":"https:\/\/www.inet.edu.ar\/index.php\/se-realizaron-capacitaciones-en-tecnologias-para-la-discapacidad-en-salta\/","title":{"rendered":"El programa PrETIS particip\u00f3 de las Jornadas de capacitaci\u00f3n en Tecnolog\u00edas para la discapacidad en la provincia de Salta"},"content":{"rendered":"<p>El lunes 25 de agosto de 2014 se desarroll\u00f3 una jornada de capacitaci\u00f3n destinada a 150 docentes y alumnos de Escuelas T\u00e9cnicas, Centros de Formaci\u00f3n Profesional\u00a0 y Escuelas de Educaci\u00f3n Especial en Salta, con la finalidad de lograr que desde las instituciones se dicten talleres de construcci\u00f3n de herramientas de ayuda t\u00e9cnica para personas con discapacidad, y as\u00ed posibilitar su inclusi\u00f3n en el sistema educativo.<\/p>\n<p>Mediante este tipo de capacitaciones y eventos se pretende lograr la construcci\u00f3n voluntaria de herramientas para distintos tipos de discapacidad, tales como aros magn\u00e9ticos para personas con problemas de hipoacusia, bastones, muletas, sillas de rueda\u00a0 y barrales, entre otros.<\/p>\n<p>El evento se realiz\u00f3 en la sede <strong>UFIDET<\/strong> de Salta Capital y cont\u00f3 con la participaci\u00f3n de la secretaria de Gesti\u00f3n Educativa, <strong>Anal\u00eda Berruezo<\/strong>, el referente del <strong>INADI<\/strong> local, <strong>Nicol\u00e1s Hirtz<\/strong>, el presidente del <strong>INTI<\/strong> local, <strong>Guillermo Baudino<\/strong>, el director de Educaci\u00f3n T\u00e9cnica, <strong>C\u00e9sar Villalobo<\/strong>, el referente jurisdiccional de <strong>INET<\/strong>, <strong>Diego L\u00f3pez Morillo<\/strong>, la coordinadora de la Modalidad Especial de la provincia, <strong>Miriam Kram<\/strong>, y el coordinador del <strong>PrETIS <\/strong>(\u201cPrograma Nacional Productivo, Tecnol\u00f3gico y Social de Ayudas T\u00e9cnicas con y para personas con discapacidad\u201d) del <strong>INET<\/strong>, <strong>Carlos Caputo<\/strong>.<\/p>\n<p>El encuentro estuvo organizado por el Ministerio de Educaci\u00f3n de la Naci\u00f3n a trav\u00e9s del Instituto Nacional de Educaci\u00f3n T\u00e9cnica <strong>(INET)<\/strong> junto con el Ministerio de Educaci\u00f3n, Ciencia y Tecnolog\u00eda de la provincia, el Instituto Nacional de Tecnolog\u00eda Industrial <strong>(INTI)<\/strong>, el Instituto Nacional contra la Discriminaci\u00f3n, la Xenofobia y el Racismo <strong>(INADI)<\/strong> y la Comisi\u00f3n Nacional Asesora para la Integraci\u00f3n de las Personas con Discapacidad <strong>(CONADIS).<\/strong><\/p>\n<p>Estas capacitaciones se llevan adelante en el marco del <strong>\u201cPrograma Nacional Productivo, Tecnol\u00f3gico y Social de Ayudas T\u00e9cnicas con y para personas con discapacidad\u201d INTI-INET-CONADIS-INADI<\/strong>.<\/p>\n<p><strong>Acerca de los aros magn\u00e9ticos<\/strong><\/p>\n<p>Los <strong>aros magn\u00e9ticos<\/strong> son amplificadores de sonido que permiten que quienes poseen hipoacusia puedan escuchar en igualdad de condiciones que el resto de las personas. Dado que el aud\u00edfono que utilizan las personas con hipoacusia es de elevado costo, desde ahora las escuelas t\u00e9cnicas tambi\u00e9n construir\u00e1n un receptor muy econ\u00f3mico dise\u00f1ado por el<strong> INTI<\/strong> que permitir\u00e1 que los ni\u00f1os y j\u00f3venes con discapacidad auditiva puedan escuchar lo emitido por el aro magn\u00e9tico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El lunes 25 de agosto de 2014 se desarroll\u00f3 una jornada de capacitaci\u00f3n destinada a 150 docentes y alumnos de Escuelas T\u00e9cnicas, Centros de Formaci\u00f3n Profesional\u00a0 y Escuelas de Educaci\u00f3n Especial en Salta, con la finalidad de lograr que desde las instituciones se dicten talleres de construcci\u00f3n de herramientas de ayuda t\u00e9cnica para personas con [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4600","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/4600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=4600"}],"version-history":[{"count":13,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/4600\/revisions"}],"predecessor-version":[{"id":18524,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/4600\/revisions\/18524"}],"wp:attachment":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=4600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=4600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=4600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}