{"id":7540,"date":"2015-06-30T17:29:04","date_gmt":"2015-06-30T20:29:04","guid":{"rendered":"https:\/\/www.inet.edu.ar\/?p=7540"},"modified":"2015-07-03T12:10:34","modified_gmt":"2015-07-03T15:10:34","slug":"se-realizo-una-importante-inversion-en-la-educacion-tecnico-profesional-en-neuquen","status":"publish","type":"post","link":"https:\/\/www.inet.edu.ar\/index.php\/se-realizo-una-importante-inversion-en-la-educacion-tecnico-profesional-en-neuquen\/","title":{"rendered":"Se realiz\u00f3 una importante inversi\u00f3n en Educaci\u00f3n T\u00e9cnico Profesional en Neuqu\u00e9n"},"content":{"rendered":"<p align=\"center\"><strong><em><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/El-Director-Ejecutivo-del-INET-con-el-Ministro-de-Educacion-y-la-Secretaria.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7541\" title=\"El Director Ejecutivo del INET con el Ministro de Educacion y la Secretaria\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/El-Director-Ejecutivo-del-INET-con-el-Ministro-de-Educacion-y-la-Secretaria-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" \/><\/a>La provincia recibi\u00f3 un aula taller m\u00f3vil y fondos para la adquisici\u00f3n de insumos para pr\u00e1cticas formativas, y reparaciones menores y equipamiento por m\u00e1s de siete millones de pesos.<\/em><\/strong><\/p>\n<p>Neuqu\u00e9n capital, martes 30 de junio de 2015.<\/p>\n<p>&nbsp;<\/p>\n<p>Con la presencia del Ministro de Desarrollo Social y Educaci\u00f3n de la provincia, <strong>Mariano Gaido<\/strong>; la secretaria de Educaci\u00f3n, <strong>Mar\u00eda Pasqualini<\/strong>; y el Director Ejecutivo del Instituto Nacional de Educaci\u00f3n Tecnol\u00f3gica (INET), <strong>Eduardo Aragundi<\/strong>; se hizo entrega de un aula taller m\u00f3vil, de la especialidad \u201cInstalaciones Domiciliarias\u201d, y se entregaron certificados de transferencia de fondos para el desarrollo de la modalidad. El acto tuvo sede en el Estadio Ruca Che de la capital neuquina.<\/p>\n<p><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">Estuvieron presentes la referente t\u00e9cnico- pol\u00edtica de la provincia, Gabriela Mabel Banino; el\u00a0Coordinador de Formaci\u00f3n Profesional del INET,\u00a0Pedro Angulo;\u00a0el presidente de la Fundaci\u00f3n del Banco Provincia del Neuqu\u00e9n, Pablo Bongiovanni; junto a directores y alumnos de establecimientos de educaci\u00f3n t\u00e9cnica.<\/span><\/p>\n<p><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">El aula taller m\u00f3vil entregada a Neuqu\u00e9n es parte de la Red Nacional Aulas Talleres M\u00f3viles que cre\u00f3 el Ministerio de Educaci\u00f3n de la Naci\u00f3n a trav\u00e9s del INET. Se trata de estructuras transportables que replican las condiciones de un aula convencional de la modalidad t\u00e9cnica, con la particularidad que, mediante un sistema de rotaci\u00f3n interna en cada provincia, estimado en cinco localidades por a\u00f1o, se trasladan e instalan en zonas de escasa poblaci\u00f3n o alejadas de las grandes urbes en donde el acceso a una Formaci\u00f3n Profesional y Capacitaci\u00f3n laboral es limitado.<\/span><\/p>\n<p><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">El Ministro Gaido dio detalles del funcionamiento que la unidad m\u00f3vil tendr\u00e1 en su provincia. Por su parte, la Prof. Pasqualini destac\u00f3 que <\/span><em style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">\u00abpropuestas como estas generan puentes hacia el mercado laboral y el conocimiento\u00bb, <\/em><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">y agreg\u00f3 que Neuqu\u00e9n<\/span><em style=\"line-height: 1.21em; font-size: 12.1599998474121px;\"> \u00abse sum\u00f3 a esta propuesta entendiendo que no existe una sociedad democr\u00e1tica y libre sin educaci\u00f3n\u00bb.<\/em><\/p>\n<p><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">En tanto, el Director Ejecutivo del INET coment\u00f3 que <\/span><em style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">\u00abla idea es llegar a aquellas personas, mayores de 16 a\u00f1os de edad, radicadas en lugares alejados que requieran Capacitaci\u00f3n laboral y Formaci\u00f3n Profesional en la modalidad t\u00e9cnica\u00bb<\/em><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">. En este sentido, indic\u00f3 que las aulas fomentan la formaci\u00f3n educativa en especialidades t\u00e9cnicas tales como: reparaci\u00f3n de motos, autos, gastronom\u00eda, instalaciones domiciliarias, indumentaria y textil, refrigeraci\u00f3n, inform\u00e1tica y redes y otras capacitaciones que apuntan a la inserci\u00f3n laboral.<\/span><\/p>\n<p><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">Durante el acto, el Ministerio de Educaci\u00f3n de la Naci\u00f3n, a trav\u00e9s del INET, entreg\u00f3 a la provincia constancias de transferencia de fondos para la Educaci\u00f3n T\u00e9cnico Profesional destinadas al desarrollo de Infraestructura, Reparaciones Menores, Equipamiento y Mobiliario escolar por 5.360.000 pesos. Adem\u00e1s, se firm\u00f3 la primera cuota de este a\u00f1o para la provisi\u00f3n de Insumos educativos para las pr\u00e1cticas formativas de la modalidad por 1.730.000 pesos.<\/span><\/p>\n<p><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">Estas acciones se suman a todas las pol\u00edticas educativas desarrolladas a lo largo del pa\u00eds en pos de la mejora y el fortalecimiento de la modalidad t\u00e9cnica.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Para m\u00e1s informaci\u00f3n<\/span><\/strong><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/politicas-y-programas\/programa-federal-de-aulas-tecnicas-moviles\/\" target=\"_blank\">Enlace WEB INET Red Nacional Aulas Talleres M\u00f3viles<\/a><\/p>\n<p><a href=\"http:\/\/redatm.inet.edu.ar\/\" target=\"_blank\">Web Red Nacional Aulas Talleres M\u00f3viles<\/a><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/politicas-y-programas\/insumos-educativos-para-la-educacion-tecnico-profesional\/\" target=\"_blank\">Enlace WEB INET- Insumos educativos<\/a><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/politicas-y-programas\/fondo-para-reparaciones-menores-equipamiento-y-mobiliario-escolar\/\" target=\"_blank\">Enlace WEB INET &#8211; Reparaciones menores, equipamiento y mobiliario escolar<\/a><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/noticias\/la-presidenta-de-la-nacion-anuncio-una-nueva-inversion-para-la-infraestructura-educativa-que-beneficiara-a-escuelas-tecnicas-de-todo-el-pais-2\/\" target=\"_blank\">Noticia \u201cLa Presidenta de la Naci\u00f3n anunci\u00f3 una nueva inversi\u00f3n para la infraestructura educativa que beneficiar\u00e1 a escuelas t\u00e9cnicas de todo el pa\u00eds\u201d<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"text-decoration: underline;\">Noticias relacionadas<\/span><\/strong><\/p>\n<p><a href=\"http:\/\/www.ministerionqn.gob.ar\/mas-infraestructura-y-fondos-para-potenciar-la-educacion-tecnica\/#prettyPhoto\" target=\"_blank\">WEB Ministerio de Gobierno y Educaci\u00f3n de Neuqu\u00e9n<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"text-decoration: underline;\"><strong>Galer\u00eda de im\u00e1genes<\/strong><\/span><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Dentro-de-una-ATM.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7555\" title=\"Dentro de una ATM\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Dentro-de-una-ATM-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Dentro-de-una-ATM-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Dentro-de-una-ATM-240x162.jpg 240w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Nueva-Aula-Taller-en-Neuquen.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7542\" title=\"Nueva-Aula-Taller-en Neuquen\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Nueva-Aula-Taller-en-Neuquen-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Ministro-Gaido-con-Prof.-Aragundi-y-Prof.-Pasquialini-y-Arq.-Angulo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7554\" title=\"Ministro Gaido con Prof. Aragundi y Prof. Pasquialini y Arq. Angulo\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Ministro-Gaido-con-Prof.-Aragundi-y-Prof.-Pasquialini-y-Arq.-Angulo-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Ministro-Gaido-con-Prof.-Aragundi-y-Prof.-Pasquialini-y-Arq.-Angulo-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Ministro-Gaido-con-Prof.-Aragundi-y-Prof.-Pasquialini-y-Arq.-Angulo-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Ministro-Gaido-con-Prof.-Aragundi-y-Prof.-Pasquialini-y-Arq.-Angulo-468x312.jpg 468w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/06\/Ministro-Gaido-con-Prof.-Aragundi-y-Prof.-Pasquialini-y-Arq.-Angulo.jpg 819w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La provincia recibi\u00f3 un aula taller m\u00f3vil y fondos para la adquisici\u00f3n de insumos para pr\u00e1cticas formativas, y reparaciones menores y equipamiento por m\u00e1s de siete millones de pesos. Neuqu\u00e9n capital, martes 30 de junio de 2015. &nbsp; Con la presencia del Ministro de Desarrollo Social y Educaci\u00f3n de la provincia, Mariano Gaido; la secretaria [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":7541,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7540"}],"version-history":[{"count":5,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7540\/revisions"}],"predecessor-version":[{"id":7553,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7540\/revisions\/7553"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/7541"}],"wp:attachment":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}