{"id":7564,"date":"2015-07-03T13:45:59","date_gmt":"2015-07-03T16:45:59","guid":{"rendered":"https:\/\/www.inet.edu.ar\/?p=7564"},"modified":"2015-07-03T15:08:39","modified_gmt":"2015-07-03T18:08:39","slug":"chaco-el-gobernador-el-ministro-de-educacion-de-la-provincia-y-el-director-ejecutivo-del-inet-dieron-apertura-a-tecnicamente","status":"publish","type":"post","link":"https:\/\/www.inet.edu.ar\/index.php\/chaco-el-gobernador-el-ministro-de-educacion-de-la-provincia-y-el-director-ejecutivo-del-inet-dieron-apertura-a-tecnicamente\/","title":{"rendered":"Chaco: El Gobernador, el Ministro de Educaci\u00f3n de la provincia, y el Director Ejecutivo del INET dieron apertura a T\u00e9cnicaMente"},"content":{"rendered":"<p align=\"center\"><em><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Gobernador-Ministro-de-Educacion-y-Director-Ejecutivo-del-INET.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7565\" title=\"Gobernador, Ministro de Educacion y Director Ejecutivo del INET\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Gobernador-Ministro-de-Educacion-y-Director-Ejecutivo-del-INET-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Gobernador-Ministro-de-Educacion-y-Director-Ejecutivo-del-INET-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Gobernador-Ministro-de-Educacion-y-Director-Ejecutivo-del-INET-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Gobernador-Ministro-de-Educacion-y-Director-Ejecutivo-del-INET-468x312.jpg 468w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Se entregaron adem\u00e1s dos aulas talleres m\u00f3viles<\/em><\/p>\n<p><span style=\"line-height: 1.21em; font-size: 12.1599998474121px;\">Resistencia, 02 de julio de 2015<\/span><\/p>\n<p>El gobernador <strong>Cr. Jorge Capitanich<\/strong>; el Ministro de Educacion, Cultura, Ciencia y Tecnolog\u00eda, <strong>Prof. Sergio Soto<\/strong>; y el Director Ejecutivo del Instituto Nacional de Educaci\u00f3n Tecnol\u00f3gica (INET), <strong>Prof. Eduardo Aragundi<\/strong>, encabezaron el acto de apertura del Encuentro T\u00e9cnicaMente, en su instancia regional, en Chaco. El evento tuvo sede en el Centro de Convenciones \u00abGala\u00bb. Durante el acto, se entregaron dos aulas talleres m\u00f3viles.<\/p>\n<p>Estuvieron presentes la Presidenta de la Comisi\u00f3n de Educaci\u00f3n de la C\u00e1mara de Diputados provincial, <strong>Dip. Nancy Mariel Gerzel<\/strong>, junto con el Coordinador de Formaci\u00f3n Profesional del INET, <strong>Arq. Pedro Angulo<\/strong>. Asistieron tambi\u00e9n los referentes t\u00e9cnico-pol\u00edticos de la Comisi\u00f3n Federal para la ETP de Chaco, Santiago del Estero y de Formosa.<\/p>\n<p>El <strong>Cr. Capitanich<\/strong> manifest\u00f3 su orgullo como provincia anfitriona de recibir delegaciones de Formosa, Salta, y Santiago del Estero. Declar\u00f3 que la existencia de los stands exhibiendo los trabajos realizados por los estudiantes permite <em>\u00abverificar el avance cuantitativo de la Educaci\u00f3n T\u00e9cnica\u00bb<\/em>. En este sentido, consider\u00f3 que <em>\u201cpara el desarrollo del modelo industrial de pa\u00eds que se puso en marcha en 2003, se necesita la formaci\u00f3n t\u00e9cnica de recursos calificados y hoy esta muestra y estos trabajos son reflejo de ello\u201d<\/em>.<em> <\/em>En relaci\u00f3n al desarrollo de la modalidad, Capitanich manifest\u00f3 que fue durante estos a\u00f1os que se logr\u00f3 <em>\u00abla recuperaci\u00f3n de un modelo de pa\u00eds con mayores recursos para la Educaci\u00f3n, especialmente para la Educaci\u00f3n T\u00e9cnico Profesional\u00bb<\/em>. Tales recursos se volcaron a lo largo y ancho del pa\u00eds en infraestructura para establecimientos educativos y adquisici\u00f3n de nuevo equipamiento. <em>\u201cRecuerdo que antes se ense\u00f1aban elementos como el torno mediante fotos e im\u00e1genes; en cambio ahora, los alumnos pueden manejar las m\u00e1quinas y herramientas ellos mismos. Esto es posible gracias a la decisi\u00f3n de nuestra Presidenta que destin\u00f3 los recursos necesarios para el desarrollo de este tipo de formaci\u00f3n\u201d<\/em>, subray\u00f3. Por \u00faltimo, el gobernador asever\u00f3 que la Argentina <em>\u201cha podido desarrollarse gracias a que hay T\u00e9cnicos\u00bb<\/em>.<\/p>\n<p>Por su parte, el <strong>Prof. Aragundi<\/strong> manifest\u00f3 que <em>\u00abla Argentina destina hoy el porcentaje m\u00e1s alto del PBI de su historia a la Educaci\u00f3n, el 6%, lo que significa la mayor inversi\u00f3n de la historia\u201d<\/em>. Asimismo, agreg\u00f3 que el 70% de egresados de la modalidad \u00ab<em>sigue estudiando o entra a un mercado laboral cada vez m\u00e1s exigente\u00bb<\/em>. En relaci\u00f3n a T\u00e9cnicaMente, consider\u00f3 que <em>\u00abmejor que decir es hacer, por eso, a trav\u00e9s de esta gran muestra, nos gusta mostrar lo que se hace en nuestras escuelas t\u00e9cnicas y centros de formaci\u00f3n profesional d\u00eda a d\u00eda&#8230; Los estudiantes son los mejores voceros de lo que se hace en Educaci\u00f3n T\u00e9cnica\u00bb<\/em>.<\/p>\n<p>Las aulas talleres m\u00f3viles entregadas por el Ministerio de Educaci\u00f3n, a trav\u00e9s del INET, a la provincia son de las especialidades Soldadura, e Inform\u00e1tica\u00a0 y Reparaci\u00f3n de PC, y se suman a la ya entregada de Instalaciones Domiciliarias. Durante este a\u00f1o, se espera la llegada de una cuarta, de Automatizaci\u00f3n Industrial. Estas unidades m\u00f3viles se instalar\u00e1n en zonas alejadas a los centros urbanos, donde la formaci\u00f3n profesional y la capacitaci\u00f3n laboral no son de f\u00e1cil acceso. De esta manera, <em>\u00abse lleva la formaci\u00f3n en oficios a lugares donde antes no se sab\u00eda c\u00f3mo llegar\u00bb<\/em> con esta capacitaci\u00f3n, como asever\u00f3 el <strong>Prof. Aragundi<\/strong> durante el acto.<\/p>\n<p>El Encuentro T\u00e9cnicaMente se extiende hasta el viernes 3. Participan m\u00e1s de 400 estudiantes, docentes y directivos de ETP de Chaco, Salta, Santiago del Estero, Formosa y Chaco exhibiendo proyectos que representan el trabajo realizado en instituciones de la modalidad durante el a\u00f1o.<\/p>\n<p>Estas acciones son parte de pol\u00edticas educativas nacionales de equidad, inclusi\u00f3n y desarrollo de la \u00faltima d\u00e9cada, y se suman a las actividades previstas para conmemorar los 10 a\u00f1os de la promulgaci\u00f3n de la Ley de Educaci\u00f3n T\u00e9cnico Profesional (N\u00b0 26.058).<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Acerca del III Encuentro Nacional de Estudiantes\u00a0 de ETP: T\u00e9cnicaMente<\/strong><\/p>\n<p>T\u00e9cnicaMente es organizado por el Ministerio de Educaci\u00f3n de la Naci\u00f3n, a trav\u00e9s del INET, junto a las 24 jurisdicciones del pa\u00eds. Estos encuentros permiten la difusi\u00f3n de las experiencias institucionales que vinculan las pr\u00e1cticas formativas,\u00a0 innovadoras y sustentables, con el medio social de las instituciones, con el medio ambiente y con el mercado productivo de su comunidad, promoviendo as\u00ed el fortalecimiento de la identidad de la Educaci\u00f3n T\u00e9cnico Profesional como productora del cambio social.<\/p>\n<p>Durante esta tercera edici\u00f3n del T\u00e9cnicaMente, y con motivo de celebrarse los 10 a\u00f1os de la Ley de Educaci\u00f3n T\u00e9cnico Profesional (N\u00b0 26.058), al mismo tiempo que se realiza la exposici\u00f3n, directivos, docentes y estudiantes participan de talleres de reflexi\u00f3n y debate sobre la modalidad.<\/p>\n<p>El Encuentro en Chaco junto con el de Entre R\u00edos durante los mismos d\u00edas son las dos \u00faltimas sedes de la instancia regional previas a la instancia nacional, prevista para el mes de octubre en la provincia de Tucum\u00e1n. En la instancia final se presentar\u00e1n aquellos trabajos seleccionados por los estudiantes en todas las instancias regionales.<\/p>\n<p><span style=\"text-decoration: underline;\">Para m\u00e1s informaci\u00f3n<\/span><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/capacitacion-publicaciones\/unidad-de-gestion-de-politicas-estudiantiles\/olimpiadas-nacionales-de-construcciones-y-electromecanica-2014\/tecnicamente\/\" target=\"_blank\">T\u00e9cnicaMente web INET<\/a><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/normativa\/ley-de-educacion-tecnico-profesional\/\" target=\"_blank\">Ley de Educaci\u00f3n T\u00e9cnico Profesional<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Acerca de la Red Nacional Aulas Talleres M\u00f3viles (ATM)<\/strong><\/p>\n<p>En el marco de una pol\u00edtica de equidad social, inclusi\u00f3n y desarrollo, en el a\u00f1o 2013 el Ministerio de Educaci\u00f3n de la Naci\u00f3n crea, a trav\u00e9s del NET,\u00a0 la Red Nacional Aulas Talleres M\u00f3viles con el objetivo principal de ampliar y facilitar el acceso a la Formaci\u00f3n Profesional y la capacitaci\u00f3n laboral a\u00a0 j\u00f3venes y adultos que actualmente deben alejarse de sus lugares de origen para lograr su formaci\u00f3n.<\/p>\n<p>Estas unidades m\u00f3viles son estructuras transportables que, mediante un sistema de rotaci\u00f3n interna en cada provincia estimado en cinco localidades por a\u00f1o. El tiempo estimado de permanencia de las unidades en cada localidad oscila entre dos y cuatro meses, dependiendo de la demanda y del tipo de cursos que ofrecen.<\/p>\n<p>Complementariamente, a trav\u00e9s de esta red, se acompa\u00f1ar\u00e1 la formaci\u00f3n de docentes e instructores de Educaci\u00f3n T\u00e9cnico Profesional, as\u00ed como la Formaci\u00f3n Profesional continua de t\u00e9cnicos y profesionales.<\/p>\n<p>Desde el a\u00f1o 2013 a la fecha se han entregado\u00a0 47 unidades m\u00f3viles. Durante el a\u00f1o 2015 est\u00e1 prevista una entrega total de 121 aulas talleres m\u00f3viles en todo el pa\u00eds.<\/p>\n<p><span style=\"text-decoration: underline;\">Para m\u00e1s informaci\u00f3n:<\/span><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/politicas-y-programas\/programa-federal-de-aulas-tecnicas-moviles\/\" target=\"_blank\">Red ATM en la p\u00e1g. web de lNET\u00a0<\/a><\/p>\n<p><a href=\"http:\/\/redatm.inet.edu.ar\/\" target=\"_blank\">P\u00e1g. web de ATM<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Noticias relacionadas<\/strong><\/p>\n<p><a href=\"http:\/\/www.prensa.chaco.gov.ar\/?pag=noticia&amp;nid=37431\" target=\"_blank\">Portal de la Secretaria de prensa del gobierno de Chaco<\/a><\/p>\n<p><a href=\"http:\/\/educacion.chaco.gov.ar\/detalle-noticia\/99\" target=\"_blank\">Portal del Ministerio de Educaci\u00f3n, Cultura, Ciencia y Tecnolog\u00eda de Chaco<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Galer\u00eda de im\u00e1genes<\/strong><\/p>\n<p><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Min.-Soto-y-Prof.-Aragundi-visitando-stands.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7575\" title=\"Min. Soto y Prof. Aragundi visitando stands\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Min.-Soto-y-Prof.-Aragundi-visitando-stands-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Acto.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7568\" title=\"Acto\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Acto-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Acto-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Acto-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Acto-468x312.jpg 468w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Dentro-de-una-ATM.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7569\" title=\"Dentro de una ATM\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Dentro-de-una-ATM-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Dentro-de-una-ATM-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Dentro-de-una-ATM-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Dentro-de-una-ATM-468x312.jpg 468w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Prof.-Aragundi-visitando-stands.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7572\" title=\"Prof. Aragundi visitando stands\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Prof.-Aragundi-visitando-stands-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Prof.-Aragundo-visitando-stands-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7573\" title=\"Prof. Aragundo visitando stands 2\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Prof.-Aragundo-visitando-stands-2-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Prof.-Aragundi-visitando-stands-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-7574\" title=\"Prof. Aragundi visitando stands 3\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2015\/07\/Prof.-Aragundi-visitando-stands-3-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se entregaron adem\u00e1s dos aulas talleres m\u00f3viles Resistencia, 02 de julio de 2015 El gobernador Cr. Jorge Capitanich; el Ministro de Educacion, Cultura, Ciencia y Tecnolog\u00eda, Prof. Sergio Soto; y el Director Ejecutivo del Instituto Nacional de Educaci\u00f3n Tecnol\u00f3gica (INET), Prof. Eduardo Aragundi, encabezaron el acto de apertura del Encuentro T\u00e9cnicaMente, en su instancia regional, [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":7565,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-7564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=7564"}],"version-history":[{"count":6,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7564\/revisions"}],"predecessor-version":[{"id":7571,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/7564\/revisions\/7571"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/7565"}],"wp:attachment":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=7564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=7564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=7564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}