{"id":9078,"date":"2016-01-28T15:28:22","date_gmt":"2016-01-28T18:28:22","guid":{"rendered":"https:\/\/www.inet.edu.ar\/?p=9078"},"modified":"2016-01-29T14:54:40","modified_gmt":"2016-01-29T17:54:40","slug":"se-realizo-el-segundo-encuentro-del-ciclo-de-reuniones-entre-el-conetyp-y-empresas-del-sector-socio-productivo","status":"publish","type":"post","link":"https:\/\/www.inet.edu.ar\/index.php\/se-realizo-el-segundo-encuentro-del-ciclo-de-reuniones-entre-el-conetyp-y-empresas-del-sector-socio-productivo\/","title":{"rendered":"Se realiz\u00f3 el segundo encuentro del Ciclo de reuniones entre el CoNETyP y empresas del Sector socio productivo"},"content":{"rendered":"<p><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/ciclo-de-encuentros-entre-conetyp-y-empresarios..jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-9079\" title=\"Ciclo de encuentros entre CoNETyP y empresarios.\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/ciclo-de-encuentros-entre-conetyp-y-empresarios.-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/ciclo-de-encuentros-entre-conetyp-y-empresarios.-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/ciclo-de-encuentros-entre-conetyp-y-empresarios.-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/ciclo-de-encuentros-entre-conetyp-y-empresarios.-468x312.jpg 468w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a>Ciudad Aut\u00f3noma de Buenos Aires, 28 de enero de 2016<\/p>\n<p>El director ejecutivo del Instituto Nacional de Educaci\u00f3n Tecnol\u00f3gica (INET), <strong>Gabriel S\u00e1nchez Zinny<\/strong>, y el secretario permanente del Consejo Nacional de Educaci\u00f3n, Trabajo y Producci\u00f3n (CoNETyP), <strong>Santiago de la Barrera<\/strong>, encabezaron un encuentro con referentes de diferentes empresas del pa\u00eds. El evento tuvo lugar en la sede del INET, en la Ciudad Aut\u00f3noma de Buenos Aires.<\/p>\n<p>Esta reuni\u00f3n forma parte de un ciclo de encuentros que establece el CoNETyP y empresarios con el objetivo de adecuar las ofertas educativas, y afianzar el v\u00ednculo entre el sector socio productivo y las instituciones t\u00e9cnicas a trav\u00e9s de dos ejes: la capacitaci\u00f3n docente y las pr\u00e1cticas profesionalizantes.<\/p>\n<p>Participaron de la reuni\u00f3n la directora del nivel Secundario T\u00e9cnico del INET, <strong>Mercedes Blanco<\/strong>, y\u00a0la coordinadora del \u00e1rea de Educaci\u00f3n de la Asociaci\u00f3n Empresaria Argentina (AEA),\u00a0<strong>Cecilia Pasman<\/strong>.<\/p>\n<p>Los referentes empresariales que asistieron al evento forman parte de las siguientes compa\u00f1\u00edas: Arcor; Banco Santander R\u00edo; Bayer; Cablevisi\u00f3n; Edesur; Fiat Chrysler Automobiles; Fundaci\u00f3n Siemens; PSA Peugeot Citro\u00ebn Argentina; y Tenaris.<\/p>\n<p>Durante el evento, el director ejecutivo del INET manifest\u00f3 la importancia de trabajar en conjunto para elevar la calidad educativa de los alumnos de la modalidad. <em>\u201cLa calidad educativa tiene que ver con la empleabilidad (\u2026) La oferta educativa debe necesariamente relacionarse con demanda laboral de cada regi\u00f3n\u201d<\/em>. Y consider\u00f3 que el aumento de las pr\u00e1cticas profesionalizantes ayudar\u00e1 a aumentar la tasa de graduaci\u00f3n en las instituciones de ETP. <em>\u201cPara ello\u201d<\/em>, agreg\u00f3, <em>\u201cqueremos abrir un di\u00e1logo y escuchar sugerencias sobre todo en la vinculaci\u00f3n con la demanda laboral\u201d<\/em>.<\/p>\n<p>Durante el encuentro, los referentes empresariales compartieron las acciones que sus compa\u00f1\u00edas realizan con instituciones t\u00e9cnicas en cuanto a formaci\u00f3n docente y a las pr\u00e1cticas profesionalizantes de los estudiantes de la modalidad.<\/p>\n<p>Finalmente, el secretario del CoNETyP sostuvo que el objetivo fundamental de la gesti\u00f3n del INET es trabajar intensamente en los asuntos federales, articulando pol\u00edticas educativas, y adecuando en forma permanente la calidad educativa de cada especialidad t\u00e9cnica al mundo productivo de cada regi\u00f3n.<\/p>\n<p><strong>Acerca del CoNETyP<\/strong><\/p>\n<p>El CoNETyP (Consejo Nacional de Educaci\u00f3n, Trabajo y Producci\u00f3n) es un \u00f3rgano consultivo y propositivo (creado por la Ley de Educaci\u00f3n T\u00e9cnico Profesional N\u00b0 26.058 sobre la base del Consejo Nacional de Educaci\u00f3n-Trabajo) cuya finalidad es asesorar al Ministro de Educaci\u00f3n y Deportes en todos los aspectos relativos al desarrollo y fortalecimiento de la educaci\u00f3n t\u00e9cnico profesional, y articular las pol\u00edticas de Educaci\u00f3n T\u00e9cnico Profesional con las de otras \u00e1reas del Estado.<\/p>\n<p><strong><a href=\"https:\/\/www.inet.edu.ar\/institucional\/conetyp\/\" target=\"_blank\">M\u00e1s informaci\u00f3n<\/a> <\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Enlaces de inter\u00e9s:<\/strong><\/p>\n<p><a href=\"http:\/\/www.aeanet.net\/que-es-aea\/#.VqpGKtDQO9o\" target=\"_blank\">Sitio web de AEA (Asociaci\u00f3n Empresaria Argentina) <\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Galer\u00eda de im\u00e1genes<\/strong><\/p>\n<p><strong><\/strong><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-9083\" title=\"reunion conetyp y AEA (1)\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-1-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-1-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-1-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-1-468x312.jpg 468w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-9084\" title=\"Almuerzo conetyp y AEA (2)\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-2-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-2-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-2-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-2-468x312.jpg 468w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><a href=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-9085\" title=\"reunion conetyp y AEA (3)\" src=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-3-150x100.jpg\" alt=\"\" width=\"150\" height=\"100\" srcset=\"https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-3-150x100.jpg 150w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-3-240x160.jpg 240w, https:\/\/www.inet.edu.ar\/wp-content\/uploads\/2016\/01\/reunion-conetyp-y-AEA-3-468x312.jpg 468w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciudad Aut\u00f3noma de Buenos Aires, 28 de enero de 2016 El director ejecutivo del Instituto Nacional de Educaci\u00f3n Tecnol\u00f3gica (INET), Gabriel S\u00e1nchez Zinny, y el secretario permanente del Consejo Nacional de Educaci\u00f3n, Trabajo y Producci\u00f3n (CoNETyP), Santiago de la Barrera, encabezaron un encuentro con referentes de diferentes empresas del pa\u00eds. El evento tuvo lugar en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":9079,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-9078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/9078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/comments?post=9078"}],"version-history":[{"count":6,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/9078\/revisions"}],"predecessor-version":[{"id":9089,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/posts\/9078\/revisions\/9089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media\/9079"}],"wp:attachment":[{"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/media?parent=9078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/categories?post=9078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.inet.edu.ar\/index.php\/wp-json\/wp\/v2\/tags?post=9078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}